{"id":4412,"date":"2024-10-10T10:20:15","date_gmt":"2024-10-10T08:20:15","guid":{"rendered":"https:\/\/ungedient.de\/blog\/?p=4412"},"modified":"2024-10-12T21:51:53","modified_gmt":"2024-10-12T19:51:53","slug":"bereit-sein-ist-alles-vdrbw","status":"publish","type":"post","link":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/","title":{"rendered":"Bereit sein ist alles."},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css=&#8220;.vc_custom_1728593780081{background-color: #000000 !important;border-radius: 3px !important;}&#8220;][vc_column][vc_video link=&#8220;https:\/\/www.youtube.com\/watch?v=uhkHptKKnvo&#8220; el_aspect=&#8220;235&#8243; css=&#8220;.vc_custom_1728593904875{margin-top: 0px !important;padding-top: 0px !important;}&#8220;][vc_row_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;.vc_custom_1728601404059{margin-top: -10px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-right: 10px !important;padding-bottom: 10px !important;padding-left: 10px !important;}&#8220; el_class=&#8220;lightbright&#8220;]Am 10.10.2024 wurde das neue Imagevideo des Reservistenverbandes ver\u00f6ffentlicht. Ich pers\u00f6nlich finde es gelungen \u2013 und meine, zugegeben nicht gerade hohen, Erwartungen wurden \u00fcbertroffen. Allerdings gibt es durchaus auch berechtigte Kritik von Interessierten und Kameraden: Repr\u00e4sentiert das Video wirklich den Reservistenverband oder eher das was er gerne w\u00e4re? Nun, vielleicht ist es ja eine sich selbst erf\u00fcllende Prophezeiung. Faktisch ist der Reservistenverband viel vielseitiger als ein kurzes Imagevideo es darstellen k\u00f6nnte. Das Video zeigt eine Ausbildung im Gr\u00fcnen, eine Art Biwak, nur ohne Waffen. Das hat nat\u00fcrlich seine Gr\u00fcnde und auch Blueguns (Waffenattrappen) h\u00e4tten es vermutlich nicht besser gemacht. Doch geh\u00f6rt zum &#8222;Gr\u00fcnen&#8220; auch irgendwie das G36 dazu &#8211; denn ansonsten ist das gezeigte doch sehr variabel. Wie ein User aus der <a href=\"https:\/\/ungedient.de\/blog\/neuigkeiten\/whatsapp\/\">Ungedient-Community<\/a> schreibt h\u00e4tte das Video, wenn man die Uniformen tauschen w\u00fcrde, ebenso gut von THW oder Feuerwehr sein k\u00f6nnen. Hat die Agentur den Kunden verstanden &#8211; oder macht sie eben das was sie gut kann? Zur\u00fcck zur Frage: Warum wurden keine Waffen gezeigt? Manche meinen, dass man vielleicht niemanden erschrecken wollte, doch ich denke nicht, dass das der Grund daf\u00fcr ist. Vielmehr ist es so, dass hier die Trennung zwischen der beorderten und der unbeorderten Reserve deutlich sichtbarer wird als man es oftmals m\u00f6chte: ohne Bundeswehr gibt&#8217;s eben keine Waffen. Als das Imagevideo auf YouTube ver\u00f6ffentlicht wurde erreichte es innerhalb von 10 Stunden nur 7.500 Aufrufe und weniger als 120 Daumen nach oben. Ich hoffe, dass der Verband noch mehr Reichweite f\u00fcr sein Geld bekommt.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243; css=&#8220;.vc_custom_1728762372810{margin-top: -10px !important;padding-right: 10px !important;padding-left: 10px !important;}&#8220;][vc_column_text css=&#8220;&#8220; el_class=&#8220;lightbright &#8222;]\n<p style=\"text-align: left;\">Warum bist du Teil der Reserve oder m\u00f6chtest es gerne\u00a0werden?<\/p>\n[\/vc_column_text][vc_single_image image=&#8220;4674&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220; style=&#8220;vc_box_rounded&#8220; css=&#8220;&#8220;][vc_column_text css=&#8220;&#8220; el_class=&#8220;lightbright smalx&#8220;]\n<p style=\"text-align: center;\"><small>Quelle: Meinungsbild innerhalb<br \/>\nder <a href=\"https:\/\/ungedient.de\/blog\/neuigkeiten\/whatsapp\/\">Ungedient.de-Community<\/a>.<\/small><\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_tta_accordion style=&#8220;modern&#8220; color=&#8220;black&#8220; active_section=&#8220;100&#8243;][vc_tta_section title=&#8220;Detaillierte Rezension\u2026&#8220; tab_id=&#8220;1728597409565-ab0b48e1-9a67&#8243;][vc_column_text css=&#8220;&#8220;]<em><strong>Es folgt eine pers\u00f6nliche Interpretation des Imagevideos.<\/strong> <\/em>Das Video beginnt mit 16 Kameradinnen und Kameraden, welche aus einem Nadelwald auf eine Lichtung heraustreten. Im Hintergrund h\u00f6rt man ein urt\u00fcmliches Schlachthorn, wie man es von Gondor aus <em>Herr der Ringe<\/em> kennt. Durch die leichte Verlangsamung wird der Augenblick noch ein wenig epischer. Die Protagonisten geben ein recht diverses Bild ab: ein Querschnitt durch die Gesellschaft. W\u00fcrde meine Reservistenkameradschaft aus dem Wald treten, dann w\u00fcrde das allerdings etwas anders aussehen&#8230; Aber gut. Es folgen Portraitaufnahmen, welche die Vielfalt und Aufgeschlossenheit des VdRBw vermitteln sollen. Naja und eben transportieren, dass der Verband Charakter hat. Dann wird die Frage gestellt, welche der Clip beantworten m\u00f6chte: <strong>\u201eWarum du Teil der Reserve werden solltest?\u201c<\/strong> In dieser Frage steckt bereits viel Interpretationspotential: erstens wird der Zuschauer direkt mit einem kameradschaftlichen &#8222;Du&#8220; angesprochen, das war eine bewusste Entscheidung der Regie, um dynamisch, aufgeschlossen und pers\u00f6nlicher zu sein. Zweitens &#8222;Teil von etwas sein&#8220; zahlt in das Gef\u00fchl von Identit\u00e4t und Wertsch\u00e4tzung ein &#8211; das gibt Sympathiepunkte. Drittens &#8222;der Reserve&#8220; &#8211; man <i>beansprucht <\/i>den Begriff &#8222;Reserve&#8220; f\u00fcr sich &#8211; das ist selbstbewusst, etwas unscharf, aber nicht falsch. (Dies kommt auch nochmal zu einem sp\u00e4teren Zeitpunkt, n\u00e4mlich ganz am Schluss bei der neuen Logoanimation.) Dann folgen die &#8222;Argumente&#8220;, warum man nun Teil der Reserve werden m\u00f6chte bzw. sollte.<\/p>\n<p><strong>Weil du gerne Gruppenreisen unternimmst.<\/strong><br \/>\nMachen wir uns ehrlich: mit dem Wolf, dem Gel\u00e4ndewagen, mit Y-Kennzeichen verlegen wir doch im Rahmen der Reservistenkameradschaft eher selten. Selbst im Heimatschutz sind gr\u00fcne Fahrzeuge eine kleine Besonderheit. Dazu kommt, dass es sich um ein dienstliches Fahrzeug handelt&#8230; also irgendwie seltsam. Mich spricht das Argument \u00fcberhaupt nicht an, weil ich bei Gruppenreisen an Kaffeefahrten denken muss. Aber man kann es auch einfach so deuten, dass man eben gemeinsam etwas unternimmt.<\/p>\n<p><strong>Weil du gerne strammstehst.<\/strong><br \/>\nEcht? Gibt es jemanden der das wirklich richtig gerne macht?<\/p>\n<p><strong>Weil du Herausforderungen liebst.<\/strong><br \/>\nDa gehe ich mit. Herausforderungen sind immer gut, solange es keine Probleme sind. Andererseits klingt es aber auch nach Abenteuerspielchen im Wald&#8230;<\/p>\n<p><strong>Weil du Perspektivwechsel brauchst.<\/strong><br \/>\nEbenfalls ein starkes Argument f\u00fcr mich, wenn auch in einem anderen Kontext: bei Vortr\u00e4gen zu Afghanistan, \u00fcber die Flugabwehr mit Gepard oder durch sicherheitspolitischen Vortr\u00e4gen des Verbandes habe ich meinen Horizont erweitert und neue Perspektiven kennengelernt. Ja, selbst bei Stammtischgespr\u00e4chen finde ich diesen Aspekt einen echten Mehrwert.<\/p>\n<p><strong>Weil du gerne mal abtauchst.<\/strong><br \/>\nIch denke da ist dem Werbetexter einfach nichts besseres eingefallen. Aber um fair zu sein: auch das ist tats\u00e4chlich ein Mehrwert. Sich mit den Kameraden mal aus dem gewohnten Umfeld auszuklinken und das Wochenende im Wald zu verbringen tut der Seele gut. Digital detox!<\/p>\n<p><strong>Weil du Kameradschaft liebst.<\/strong><br \/>\nKlar. Wer w\u00fcrde das verneinen. Aber die wenigsten &#8222;au\u00dferhalb&#8220; k\u00f6nnen mit diesem Begriff wirklich etwas anfangen.<\/p>\n<p><strong>Weil du Freundschaften f\u00fcrs Leben schlie\u00dft.<\/strong><br \/>\nWer m\u00f6chte das nicht? Ein gutes Argument, gilt aber f\u00fcr jeden Verein.<\/p>\n<p><strong>Weil du gern fr\u00fch aufstehst.<\/strong><br \/>\nEcht jetzt?<\/p>\n<p><strong>Weil es viel zu verteidigen gibt.<\/strong><br \/>\nInsbesondere durch die eingeblendeten Bilder und das Ger\u00e4usch eines lachenden Kindes nat\u00fcrlich ein leichtes Spiel f\u00fcr den Werbemenschen. Wer w\u00fcrde dieses Argument nicht z\u00e4hlen lassen?<\/p>\n<p><strong>Weil wir unsere Freiheit lieben. Alle Freiheiten.<br \/>\n<\/strong>Dieses letzte Argument soll vermutlich das st\u00e4rkste sein und ist es sicherlich auch. &#8222;Demokratische Werte wertsch\u00e4tzen&#8220; ist zu sperrig, aber darum geht es.<\/p>\n<p><strong>Weil wir die st\u00e4rkste Friedensbewegung Deutschlands sind.<\/strong><br \/>\nDas ist nat\u00fcrlich eine provokante These, welche ich pers\u00f6nlich vertrete, aber sicherlich auch Kritiker hervorbringen wird. So konnte man aber auch noch sch\u00f6n verarbeiten, dass Reservisten eben keine Kriegstreiber sind, im Gegenteil.<\/p>\n<p>Der Werbeclip schlie\u00dft mit dem Slogan &#8222;Bereit sein ist alles&#8220; und erinnert mich an das Pfadfinder-Motto &#8222;Allzeit bereit&#8220;. Dann kommt noch das i-T\u00fcpfelchen, der &#8222;Call to Action&#8220;: Werde Mitglied. Als Abbinder folgt eine Logoanimation, welche ebenfalls \u00fcberarbeitet wurde und auch ein angepasstes VdRBw-Logo enth\u00e4lt. Offenbar hat auch dieses im Rahmen der Kampagne eine \u00dcberarbeitung erfahren. Der alte Slogan des VdRBw war &#8222;Wir sind die Reserve&#8220;, dies wird nun reduziert auf &#8222;Die Reserve&#8220;. Dadurch entf\u00e4llt das &#8222;wir&#8220;, aber das finde ich nun nicht weiter tragisch. Geschickt finde ich an der Animation, dass man zun\u00e4chst einen Schild wahrnimmt und dieser sich dann zum Wappen f\u00fcllt. Subtil vermittelt dies Schutz, aber ich m\u00f6chte mir nicht anma\u00dfen nun ins Tiefenpsychologische abzudriften.<\/p>\n<p>Abschlie\u00dfend noch die Show Notes, also der Text unterhalb des YouTube-Videos:<\/p>\n<blockquote><p><strong>Warum du Teil der Reserve werden solltest? Weil wir die st\u00e4rkste Friedensbewegung Deutschlands sind.<\/strong><\/p>\n<p><em>Am 24. Februar 2022 begann Wladimir Putin seinen Angriffskrieg gegen die Ukraine. Sp\u00e4testens seitdem wissen wir, dass Frieden keine Selbstversta\u0308ndlichkeit mehr ist. F\u00fcr eine wirkungsvolle Abschreckung braucht Deutschland eine starke Reserve. Der Verband der Reservisten der Deutschen Bundeswehr e. V. st\u00e4rkt mit 110.000 Mitgliedern und Veranstaltungen aus den Bereichen der Milit\u00e4rischen Ausbildung, Sicherheitspolitik und \u00d6ffentlichkeitsarbeit in ganz Deutschland die Wehrhaftigkeit unsere Landes. Du mo\u0308chtest unsere Freiheit schu\u0308tzen? Du mo\u0308chtest gern Verantwortung fu\u0308r die Demokratie und Sicherheit in Deutschland u\u0308bernehmen? Du mo\u0308chtest Kameradschaft erleben? Du mo\u0308chtest dich weiterbilden und bist offen fu\u0308r Neues? Du hast bei der Bundeswehr gedient oder hast Interesse, deine Kenntnisse u\u0308ber die Bundeswehr und milita\u0308rische Zusammenha\u0308nge zu erweitern? Du hast Lust, dich zusammen mit einem starken Team fu\u0308r unser Land zu engagieren und dein Wissen einzubringen? Dann werde Mitglied in unserem Verband. Denn bereit sein ist alles!<\/em><\/p><\/blockquote>\n[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][vc_images_carousel images=&#8220;4548,4549,4550,4551,4552,4553,4554,4555,4556,4557,4558,4559,4560,4561&#8243; img_size=&#8220;large&#8220; speed=&#8220;3300&#8243; autoplay=&#8220;yes&#8220; hide_pagination_control=&#8220;yes&#8220; wrap=&#8220;yes&#8220; css=&#8220;&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8220;&#8220;]Es besteht kein Zweifel: Die Bundeswehr ist auf eine starke Reserve angewiesen, um ihre zahlreichen Aufgaben effektiv zu erf\u00fcllen. Eine gut aufgestellte Reserve braucht wiederum einen starken Reservistenverband, der sie unterst\u00fctzt und in der \u00d6ffentlichkeit vertritt. Der Verteidigungsausschuss des Bundestages sieht dies ebenfalls so und hat einmalig <em>zus\u00e4tzliche<\/em> Mittel bewilligt, um eine umfassende <strong>Imagekampagne<\/strong> zu starten. Ziel war es, den Reservistenverband in einem sich wandelnden Umfeld neu zu positionieren und das <strong>Bewusstsein f\u00fcr die Bedeutung der Reserve in der Gesellschaft<\/strong> zu sch\u00e4rfen.<\/p>\n<blockquote><p>Die Kampagne f\u00e4llt auch in eine Zeit, in der sich der VdRBw f\u00fcr die hohen Zusch\u00fcsse aus Steuermitteln rechtfertigen muss.<\/p><\/blockquote>\n<p>Mit dem Motto <em>\u201eBereit sein ist alles\u201c<\/em> hat der Reservistenverband eine Kampagne ins Leben gerufen, die die Reservisten in den Mittelpunkt stellt. Es ging darum, Menschen zu zeigen, die bereit sind, sich f\u00fcr unser Land einzusetzen. Ein entscheidender Bestandteil der Kampagne war der Aufruf im Vorfeld an Reservistinnen und Reservisten, sich vor der Kamera zu engagieren. Gesucht wurden <em>Pers\u00f6nlichkeiten<\/em>, die sich f\u00fcr Film- und Fotoproduktionen zur Verf\u00fcgung stellen wollten. Dabei stand nicht die Kameraerfahrung im Vordergrund, sondern die individuelle Einstellung und Bereitschaft, ein <strong><em>Gesicht der Reserve<\/em><\/strong> zu werden.<\/p>\n<p>Die Resonanz war offenbar riesig: hunderte Reservisten meldeten sich und wollten das authentische Bild der Reserve in die \u00d6ffentlichkeit tragen. Das Shooting fand zwischen dem 2. und 15. September statt (im Norden und S\u00fcden Deutschlands). Die Teilnahme an der Kampagne war ehrenamtlich, doch wurde daf\u00fcr gesorgt, dass den Protagonisten keine Kosten entstanden: Anreise, Verpflegung und Unterkunft wurden vollst\u00e4ndig vom Verband \u00fcbernommen.<\/p>\n<blockquote><p>Das Herzst\u00fcck der Kampagne ist ein Imagefilm, der unter anderem auf diversen Video-Streaming-Plattformen zu sehen sein wird.<\/p><\/blockquote>\n<p>F\u00fcr die Teilnehmer bedeutete dies: Ihre Gesichter sind nun in ganz Deutschland pr\u00e4sent. Als bundesweite Botschafter der Reserve tragen sie dazu bei, das Bild der Bundeswehr und ihrer Reserve in der \u00d6ffentlichkeit zu pr\u00e4gen. Dank der Mittelbewilligung durch den Verteidigungsausschuss und der Zusammenarbeit mit einer renommierten Agentur aus Berlin konnte der Reservistenverband eine Imagekampagne realisieren, die die Bedeutung der Reserve in den Fokus r\u00fcckt \u2013 das sieht zumindest der <em>Pr\u00e4sident des Reservistenverbandes, Oberst d.R. Prof Dr. Patrick Sensburg so:<\/em><\/p>\n<blockquote><p>\u201eQuantensprung in der \u00d6ffentlichkeitsarbeit. Das ist das Beste, was der Verband seit langer Zeit gemacht hat.\u201c<\/p><\/blockquote>\n[\/vc_column_text][vc_zigzag][vc_column_text css=&#8220;&#8220;]\n<h2><strong>Was zuvor geschah\u2026<\/strong><\/h2>\n<p>Imagefilm von <a href=\"https:\/\/www.julianotten.de\/reserve-deutschland\" target=\"_blank\" rel=\"noopener\">Julian Otten<\/a> (2023)[\/vc_column_text][vc_video link=&#8220;https:\/\/youtu.be\/kcbKt2t8RmE?si=gm5kzfM5oWOZZfZ1&#8243; align=&#8220;center&#8220; css=&#8220;&#8220;][\/vc_column][vc_column][vc_message message_box_style=&#8220;solid&#8220; message_box_color=&#8220;grey&#8220; icon_fontawesome=&#8220;fas fa-image&#8220; css=&#8220;&#8220;]<strong>Titelbild<\/strong><br \/>\n\u00a9 Verband der Reservisten der Deutschen Bundes\u00adwehr e. V. \/ <em>glow<\/em>[\/vc_message][\/vc_column][\/vc_row]\n\r\n\t\t\t<div id=\"daexthefu-container\"\r\n\t\t\t\tclass=\"daexthefu-container daexthefu-layout-stacked daexthefu-alignment-center\"\r\n\t\t\t\tdata-post-id=\"4412\">\r\n\r\n\t\t\t\t<div class=\"daexthefu-feedback\">\r\n\t\t\t\t\t<div class=\"daexthefu-text\">\r\n\t\t\t\t\t\t<h3 class=\"daexthefu-title\">War dieser Artikel f\u00fcr dich hilfreich?<\/h3>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"daexthefu-buttons-container\">\r\n\t\t\t\t\t\t<div class=\"daexthefu-buttons\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"daexthefu-yes daexthefu-button daexthefu-button-type-icon\" data-value=\"1\">\r\n\t\t\t\t\r\n                <svg>\r\n                    <defs>\r\n                        <style>.thumb-up-cls-1{fill:#c9c9c9;}.thumb-up-cls-2{fill:#e1e1e1;}.thumb-up-cls-3{fill:#676767;}<\/style>\r\n                    <\/defs>\r\n                    <g id=\"thumb_up\">\r\n                        <path class=\"thumb-up-cls-2 daexthefu-icon-circle\" d=\"m24,3c11.58,0,21,9.42,21,21s-9.42,21-21,21S3,35.58,3,24,12.42,3,24,3m0-1C11.85,2,2,11.85,2,24s9.85,22,22,22,22-9.85,22-22S36.15,2,24,2h0Z\" \/>\r\n                        <g>\r\n                            <rect class=\"thumb-up-cls-3 daexthefu-icon-secondary-color\" x=\"10\" y=\"20\" width=\"6\" height=\"15\" rx=\"1.5\" ry=\"1.5\" \/>\r\n                            <path class=\"thumb-up-cls-1 daexthefu-icon-primary-color\" d=\"m30.57,9.06l-.49-.1c-.81-.17-1.61.35-1.78,1.16l-5.3,11.74c-.17.81,3.16,1.61,3.97,1.78l1.96.41c.81.17,1.61-.35,1.78-1.16l2.18-10.27c.34-1.61-.7-3.21-2.31-3.56Z\" \/>\r\n                            <path class=\"thumb-up-cls-1 daexthefu-icon-primary-color\" d=\"m38.17,20h-18.67c-.83,0-1.5.67-1.5,1.5v12c0,.83.67,1.5,1.5,1.5h16.27c.71,0,1.33-.5,1.47-1.21l2.4-12c.19-.93-.53-1.8-1.47-1.8Z\" \/>\r\n                        <\/g>\r\n                    <\/g>\r\n                <\/svg>\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"daexthefu-no daexthefu-button daexthefu-button-type-icon\" data-value=\"0\">\r\n\t\t\t\t\r\n                <svg>\r\n                    <defs>\r\n                        <style>.thumb-down-cls-1{fill:#c9c9c9;}.thumb-down-cls-2{fill:#e1e1e1;}.thumb-down-cls-3{fill:#676767;}<\/style>\r\n                    <\/defs>\r\n                    <g id=\"thumb_down\">\r\n                        <path class=\"thumb-down-cls-2 daexthefu-icon-circle\" d=\"m24,3c11.58,0,21,9.42,21,21s-9.42,21-21,21S3,35.58,3,24,12.42,3,24,3m0-1C11.85,2,2,11.85,2,24s9.85,22,22,22,22-9.85,22-22S36.15,2,24,2h0Z\" \/>\r\n                        <g>\r\n                            <rect class=\"thumb-down-cls-3 daexthefu-icon-secondary-color\" x=\"10\" y=\"13\" width=\"6\" height=\"15\" rx=\"1.5\" ry=\"1.5\" \/>\r\n                            <path class=\"thumb-down-cls-1 daexthefu-icon-primary-color\" d=\"m30.57,38.94l-.49.1c-.81.17-1.61-.35-1.78-1.16l-5.3-11.74c-.17-.81,3.16-1.61,3.97-1.78l1.96-.41c.81-.17,1.61.35,1.78,1.16l2.18,10.27c.34,1.61-.7,3.21-2.31,3.56Z\" \/>\r\n                            <path class=\"thumb-down-cls-1 daexthefu-icon-primary-color\" d=\"m38.17,28h-18.67c-.83,0-1.5-.67-1.5-1.5v-12c0-.83.67-1.5,1.5-1.5h16.27c.71,0,1.33.5,1.47,1.21l2.4,12c.19.93-.53,1.8-1.47,1.8Z\" \/>\r\n                        <\/g>\r\n                    <\/g>\r\n                <\/svg>\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"daexthefu-comment\">\r\n\t\t\t\t\t<div class=\"daexthefu-comment-top-container\">\r\n\t\t\t\t\t\t<label id=\"daexthefu-comment-label\" class=\"daexthefu-comment-label\"><\/label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"daexthefu-comment-character-counter-container\">\r\n\t\t\t\t\t\t\t\t<div id=\"daexthefu-comment-character-counter-number\"\r\n\t\t\t\t\t\t\t\t\tclass=\"daexthefu-comment-character-counter-number\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"daexthefu-comment-character-counter-text\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<textarea id=\"daexthefu-comment-textarea\" class=\"daexthefu-comment-textarea\"\r\n\t\t\t\t\t\t\t\tplaceholder=\"Dein Feedback\u2026\"\r\n\t\t\t\t\t\t\t\tmaxlength=\"\r\n\t\t\t\t\t\t\t\t500\t\t\t\t\t\t\t\t\t\"><\/textarea>\r\n\t\t\t\t\t<div class=\"daexthefu-comment-buttons-container\">\r\n\t\t\t\t\t\t<button class=\"daexthefu-comment-submit daexthefu-button\">senden<\/button>\r\n\t\t\t\t\t\t<button class=\"daexthefu-comment-cancel daexthefu-button\">abbrechen<\/button>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"daexthefu-successful-submission-text\">Vielen Dank!<\/div>\r\n\r\n\t\t\t<\/div>\r\n\r\n\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Die neue Imagekampagne des Reservistenverbandes\u2026<\/p>\n","protected":false},"author":1,"featured_media":4544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"status","meta":{"_helpful_status":1,"inline_featured_image":false,"footnotes":""},"categories":[20],"tags":[271],"class_list":["post-4412","post","type-post","status-publish","format-status","has-post-thumbnail","hentry","category-reserve","tag-vdrbw","post_format-post-format-status"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bereit sein ist alles. &#8226; UNgedient.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bereit sein ist alles. &#8226; UNgedient.\" \/>\n<meta property=\"og:description\" content=\"Die neue Imagekampagne des Reservistenverbandes\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/\" \/>\n<meta property=\"og:site_name\" content=\"UNgedient.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fuchs52y\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/fuchs52y\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-10T08:20:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-12T19:51:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/bereit-sein-teaser.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/\"},\"author\":{\"name\":\"Daniel\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#\\\/schema\\\/person\\\/1648f47e5e180daeaa9f15f2dd485bf5\"},\"headline\":\"Bereit sein ist alles.\",\"datePublished\":\"2024-10-10T08:20:15+00:00\",\"dateModified\":\"2024-10-12T19:51:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/\"},\"wordCount\":1857,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/bereit-sein-teaser.jpg\",\"keywords\":[\"vdrbw\"],\"articleSection\":[\"Reserve\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/\",\"url\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/\",\"name\":\"Bereit sein ist alles. &#8226; UNgedient.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/bereit-sein-teaser.jpg\",\"datePublished\":\"2024-10-10T08:20:15+00:00\",\"dateModified\":\"2024-10-12T19:51:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/bereit-sein-teaser.jpg\",\"contentUrl\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/bereit-sein-teaser.jpg\",\"width\":950,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/bereit-sein-ist-alles-vdrbw\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reserve\",\"item\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/thema\\\/reserve\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bereit sein ist alles.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/\",\"name\":\"UNgedient. Vom Ungedienten zur Bundeswehr.\",\"description\":\"Dein Weg in die Reserve der Bundeswehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#organization\"},\"alternateName\":\"Ausbildung f\u00fcr Ungediente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#organization\",\"name\":\"UNgedient. Vom Ungedienten zur Bundeswehr.\",\"alternateName\":\"Ausbildung Ungedienter zum Reservisten der Bundeswehr\",\"url\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ungedient-favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ungedient-favicon.jpg\",\"width\":520,\"height\":520,\"caption\":\"UNgedient. Vom Ungedienten zur Bundeswehr.\"},\"image\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fuchs52y\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#\\\/schema\\\/person\\\/1648f47e5e180daeaa9f15f2dd485bf5\",\"name\":\"Daniel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g\",\"caption\":\"Daniel\"},\"description\":\"Daniel absolvierte die Ausbildung f\u00fcr Ungediente 2023 in Rheinland-Pfalz und ist mittlerweile in der 5.\\\/HSchRgt 3 beordert. Er arbeitete als Reservistendienstleistender in einer Projektgruppe des Territorialen F\u00fchrungskommandos der Bundeswehr und engagiert sich als einer von zwei Beauftragten der Landesgruppe Baden-W\u00fcrttemberg des Verbandes der Reservisten der Deutschen Bundeswehr f\u00fcr die Ausbildung Ungediente. 2025 wurde er Vorsitzender der Reservistenarbeitsgemeinschaft Drohne MO. Daniel ist verheiratet und Vater von drei T\u00f6chtern.\",\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/fuchs52y\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bereit sein ist alles. &#8226; UNgedient.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/","og_locale":"de_DE","og_type":"article","og_title":"Bereit sein ist alles. &#8226; UNgedient.","og_description":"Die neue Imagekampagne des Reservistenverbandes\u2026","og_url":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/","og_site_name":"UNgedient.","article_publisher":"https:\/\/www.facebook.com\/fuchs52y","article_author":"https:\/\/facebook.com\/fuchs52y","article_published_time":"2024-10-10T08:20:15+00:00","article_modified_time":"2024-10-12T19:51:53+00:00","og_image":[{"width":950,"height":500,"url":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/bereit-sein-teaser.jpg","type":"image\/jpeg"}],"author":"Daniel","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Daniel","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/#article","isPartOf":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/"},"author":{"name":"Daniel","@id":"https:\/\/ungedient.de\/blog\/#\/schema\/person\/1648f47e5e180daeaa9f15f2dd485bf5"},"headline":"Bereit sein ist alles.","datePublished":"2024-10-10T08:20:15+00:00","dateModified":"2024-10-12T19:51:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/"},"wordCount":1857,"commentCount":0,"publisher":{"@id":"https:\/\/ungedient.de\/blog\/#organization"},"image":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/#primaryimage"},"thumbnailUrl":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/bereit-sein-teaser.jpg","keywords":["vdrbw"],"articleSection":["Reserve"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/","url":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/","name":"Bereit sein ist alles. &#8226; UNgedient.","isPartOf":{"@id":"https:\/\/ungedient.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/#primaryimage"},"image":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/#primaryimage"},"thumbnailUrl":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/bereit-sein-teaser.jpg","datePublished":"2024-10-10T08:20:15+00:00","dateModified":"2024-10-12T19:51:53+00:00","breadcrumb":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/#primaryimage","url":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/bereit-sein-teaser.jpg","contentUrl":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/bereit-sein-teaser.jpg","width":950,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/ungedient.de\/blog\/reserve\/bereit-sein-ist-alles-vdrbw\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ungedient.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Reserve","item":"https:\/\/ungedient.de\/blog\/thema\/reserve\/"},{"@type":"ListItem","position":3,"name":"Bereit sein ist alles."}]},{"@type":"WebSite","@id":"https:\/\/ungedient.de\/blog\/#website","url":"https:\/\/ungedient.de\/blog\/","name":"UNgedient. Vom Ungedienten zur Bundeswehr.","description":"Dein Weg in die Reserve der Bundeswehr","publisher":{"@id":"https:\/\/ungedient.de\/blog\/#organization"},"alternateName":"Ausbildung f\u00fcr Ungediente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ungedient.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ungedient.de\/blog\/#organization","name":"UNgedient. Vom Ungedienten zur Bundeswehr.","alternateName":"Ausbildung Ungedienter zum Reservisten der Bundeswehr","url":"https:\/\/ungedient.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ungedient.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2023\/03\/ungedient-favicon.jpg","contentUrl":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2023\/03\/ungedient-favicon.jpg","width":520,"height":520,"caption":"UNgedient. Vom Ungedienten zur Bundeswehr."},"image":{"@id":"https:\/\/ungedient.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fuchs52y"]},{"@type":"Person","@id":"https:\/\/ungedient.de\/blog\/#\/schema\/person\/1648f47e5e180daeaa9f15f2dd485bf5","name":"Daniel","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g","caption":"Daniel"},"description":"Daniel absolvierte die Ausbildung f\u00fcr Ungediente 2023 in Rheinland-Pfalz und ist mittlerweile in der 5.\/HSchRgt 3 beordert. Er arbeitete als Reservistendienstleistender in einer Projektgruppe des Territorialen F\u00fchrungskommandos der Bundeswehr und engagiert sich als einer von zwei Beauftragten der Landesgruppe Baden-W\u00fcrttemberg des Verbandes der Reservisten der Deutschen Bundeswehr f\u00fcr die Ausbildung Ungediente. 2025 wurde er Vorsitzender der Reservistenarbeitsgemeinschaft Drohne MO. Daniel ist verheiratet und Vater von drei T\u00f6chtern.","sameAs":["https:\/\/facebook.com\/fuchs52y"]}]}},"_links":{"self":[{"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/posts\/4412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/comments?post=4412"}],"version-history":[{"count":0,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/posts\/4412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/media\/4544"}],"wp:attachment":[{"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/media?parent=4412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/categories?post=4412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/tags?post=4412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}