{"id":4534,"date":"2024-10-09T13:24:18","date_gmt":"2024-10-09T11:24:18","guid":{"rendered":"https:\/\/ungedient.de\/blog\/?p=4534"},"modified":"2025-10-13T10:14:47","modified_gmt":"2025-10-13T08:14:47","slug":"leben-im-felde","status":"publish","type":"post","link":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/","title":{"rendered":"Leben im Felde"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_message message_box_style=&#8220;solid&#8220; message_box_color=&#8220;green&#8220; icon_fontawesome=&#8220;far fa-check-circle&#8220; css=&#8220;&#8220;]<strong>Update!<\/strong><br \/>\nJetzt f\u00fcr die Veranstaltung 2026 anmelden! <a href=\"https:\/\/forms.office.com\/e\/3VD9L3jeEE\">Einfach das Formular ausf\u00fcllen.<\/a>[\/vc_message][vc_column_text css=&#8220;&#8220;]Vom 03. bis 06. Oktober 2024 fand in der N\u00e4he von Rosenheim ein Biwak des Reservistenverbands statt, das dieses Jahr unter dem Titel \u201eLeben im <del>Felde<\/del> Matsch\u201c stand. Diese Veranstaltung bot nicht nur altgedienten Reservisten die M\u00f6glichkeit, ihre milit\u00e4rischen Fertigkeiten zu erweitern, sondern war auch speziell darauf ausgelegt, Ungedienten, also interessierten Zivilisten, einen Einblick in die Welt der Bundeswehr und ihrer Reserve zu erm\u00f6glichen. \u201eEs war eine einmalige Gelegenheit, ohne Vorkenntnisse direkt mitzumachen und hautnah zu erleben, wie das Leben im Felde wirklich aussieht\u201c, so eine Teilnehmerin ohne milit\u00e4rischen Hintergrund.<\/p>\n<h3>Ein verl\u00e4ngertes Wochenende im Zeichen von Natur und \u00dcberlebenstechniken<\/h3>\n<p>Trotz des schlechten Wetters \u2013 alles war matschig, der Regen prasselte unaufh\u00f6rlich \u2013 lie\u00dfen sich die rund 30 Teilnehmer nicht entmutigen. Die \u00e4u\u00dferen Bedingungen machten die Veranstaltung nur authentischer und gerechtfertigten den Titel der Ausbildung. Die Natur und der Regen stellten die improvisierten Lager und Unterk\u00fcnfte (Shelter) der Teilnehmer auf die Probe und boten den optimalen Rahmen f\u00fcr das Thema \u201e\u00dcberleben\u201c. \u201eDas Wetter war die gr\u00f6\u00dfte Herausforderung, aber es hat uns gelehrt, dass man in der Natur nicht immer perfekte Bedingungen erwarten kann\u201c, berichtete einer der Teilnehmer.<\/p>\n<p>Die Teilnehmer, insbesondere die Ungedienten, begannen das Wochenende mit den Grundlagen des milit\u00e4rischen \u00dcberlebens. Sie lernten, wie sie ihre Ausr\u00fcstung effizient packen und ihren Rucksack optimal einstellen. Diese Basics wurden direkt in die Praxis umgesetzt, und auch die Reservisten konnten von den erfrischenden Wiederholungen profitieren. \u201eEs war auch f\u00fcr uns <em>&#8218;Erdferkel&#8216;<\/em> eine gute M\u00f6glichkeit, die Grundlagen noch einmal aufzufrischen\u201c, sagte einer der Reservisten, der an der Ausbildung teilnahm. (Anm. d. Red. &#8222;Erdferkel&#8220; war der schmeichelhafte Gruppenname der Kameraden in Flecktarn.)<\/p>\n<h3>Essen aus der Natur: Essbare Pflanzen und Heilkr\u00e4uter entdecken<\/h3>\n<p>Ein besonderes Highlight des Wochenendes war die Schulung zum Thema \u201eEssbare Pflanzen und Heilkr\u00e4uter\u201c. Unter der Anleitung einer erfahrenen Ausbilderin erkundeten die Teilnehmer die umgebende Natur und lernten, essbare Pflanzen wie Springkraut, Brennnesseln, Waldsauerklee und \u00e4hm&#8230; viele, viele mehr&#8230; \u2013 zu erkennen und zu nutzen. \u201eEs ist erstaunlich, wie viel die Natur uns bietet, wenn man nur wei\u00df, worauf man achten muss\u201c, sagte eine Teilnehmerin, die zum ersten Mal an einer solchen Schulung teilnahm. Und ich pers\u00f6nlich freue mich schon auf meinen n\u00e4chsten Salat mit Springkrautsamen-Topping (oder sollte man es besser <em>&#8222;Balsam Seeds Power Food&#8220;<\/em> nennen? Jedenfalls k\u00f6stlich! Einfach mal ausprobieren!) Neben den pflanzlichen Nahrungsmitteln wurde auch der Umgang mit tierischer Notnahrung besprochen.<\/p>\n<h3>Feuer machen und Wasser aufbereiten: \u00dcberlebensf\u00e4higkeiten in der Praxis<\/h3>\n<p>Ein weiteres wichtiges Thema des Wochenendes war das Feuermachen. Mit Z\u00fcndstahl und verschiedenen Zunderarten (von <em>Birkenrinde <\/em>\u00fcber<em> Magnesium-Sp\u00e4ne<\/em> bis zum <em>wachsgetr\u00e4nkten Pionier-Tampon<\/em>) ausgestattet, konnten die Teilnehmer unter widrigen Bedingungen \u00fcben, rum probieren und schlie\u00dflich ein Feuer entz\u00fcnden. Eine Ausbildungsstation, die au\u00dferordentlich gut vorbereitet war&#8230;! Das muss man schlichtweg erlebt haben! Neben dem Feuermachen stand auch die Wassergewinnung und -aufbereitung auf dem Programm. Die Teilnehmer lernten, wie man Wasser aus der Natur gewinnt und trinkbar macht \u2013 eine essentielle F\u00e4higkeit in \u00dcberlebenssituationen.<\/p>\n<h3>Medizinische Ausbildung und Tourniquet-Drill<\/h3>\n<p>Ein weiteres Ausbildungsmodul des Biwaks war die medizinische Ausbildung, bei der der Umgang mit dem Tourniquet (TQ) ge\u00fcbt wurde. Dieser Drill vermittelte den Teilnehmern wertvolle Kenntnisse zur Erstversorgung in Notsituationen, ein Wissen, das im Ernstfall Leben retten kann. \u201eDie medizinische Ausbildung war sehr intensiv und hat mir gezeigt, wie wichtig es ist, solche Techniken zu beherrschen\u201c, sagte ein Reservist der beinahe &#8222;verblutet&#8220; w\u00e4re&#8230; (Die vor Ort anwesenden Feld\u00e4rzte durften ihr theoretisches Wissen auch direkt in der Praxis erproben: mir knallte kurz vor \u00dcbungsende ein Ast auf den Nasenr\u00fccken\u2026 \u2013 aber das ist eine andere Geschichte.)<\/p>\n<h3>Ein seltener Einblick f\u00fcr Ungediente<\/h3>\n<p>Trotz der herausfordernden Wetterbedingungen blicken alle Teilnehmer positiv auf das Wochenende zur\u00fcck. \u201eEs war anstrengend, aber unglaublich lehrreich\u201c, fasste ein ungedienter Zivilist zusammen. Die Veranstaltung bot nicht nur Reservisten die M\u00f6glichkeit, ihre F\u00e4higkeiten zu erweitern, sondern war vor allem f\u00fcr Ungediente ein wertvoller Einblick in das Leben im Felde. &#8222;Sehr vielf\u00e4ltig und sehr hohe Kompetenz und Erfahrung der Ausbilder&#8220;, lautet ein anderes Fazit, das mir im Nachgang zugeschickt wurde. Mehrere Teilnehmer berichteten mir zudem, dass sie \u00fcber den Blog von der Veranstaltung erfahren hatten &#8211; das freute mich nat\u00fcrlich besonders. Abends und zwischendurch gab immer wieder die M\u00f6glichkeit sich kennenzulernen und auszutauschen. &#8222;Auch im n\u00e4chsten Jahr wird es bestimmt wieder die M\u00f6glichkeit geben, an einer solchen Veranstaltungen teilzunehmen&#8230;&#8220;, verr\u00e4t Hauptfeldwebel d. R. Leonhardt Edelh\u00e4user, Organisationsleiter aus Traunstein. \u2013 Sobald ich mehr wei\u00df, werdet ihr es direkt erfahren! (Anm.d.Red.: Mittlerweile ist die <a href=\"https:\/\/forms.office.com\/e\/3VD9L3jeEE\">Anmeldung<\/a> m\u00f6glich!)[\/vc_column_text][vc_message message_box_style=&#8220;solid&#8220; message_box_color=&#8220;green&#8220; icon_fontawesome=&#8220;far fa-lightbulb&#8220; css=&#8220;&#8220;]<strong>Mein Tipp<\/strong><br \/>\nNur wenige Bilder sind aus Datenschutzgr\u00fcnden \u00f6ffentlich, doch diese kann man sich in dieser <a href=\"https:\/\/www.reservistenverband.de\/bayern\/oberpfalz-west\/galerie\/ausbildung-ueberleben-land-survival\/\" target=\"_blank\" rel=\"noopener\">Galerie<\/a> ansehen. Weitere Infos findet man zudem in diesem <a href=\"https:\/\/www.reservistenverband.de\/bayern\/oberpfalz-west\/aktuelles\/ueberleben-land-survival-in-oberbayern\/\" target=\"_blank\" rel=\"noopener\">Artikel des VdRBw<\/a>.[\/vc_message][\/vc_column][\/vc_row][vc_row color=&#8220;&#8220; message_box_style=&#8220;solid&#8220; style=&#8220;rounded&#8220; message_box_color=&#8220;grey&#8220; icon_type=&#8220;fontawesome&#8220; icon_fontawesome=&#8220;fas fa-image&#8220; icon_monosocial=&#8220;vc-mono vc-mono-fivehundredpx&#8220; icon_openiconic=&#8220;&#8220; icon_typicons=&#8220;&#8220; icon_entypo=&#8220;&#8220; icon_linecons=&#8220;&#8220; icon_pixelicons=&#8220;&#8220;][vc_column][vc_message message_box_style=&#8220;solid&#8220; message_box_color=&#8220;grey&#8220; icon_fontawesome=&#8220;fas fa-image&#8220; css=&#8220;&#8220;]<strong>Titelbild<\/strong><br \/>\n\u00a9 Benjamin Kunder \/ eigene Montage[\/vc_message][\/vc_column][\/vc_row]\n\r\n\t\t\t<div id=\"daexthefu-container\"\r\n\t\t\t\tclass=\"daexthefu-container daexthefu-layout-stacked daexthefu-alignment-center\"\r\n\t\t\t\tdata-post-id=\"4534\">\r\n\r\n\t\t\t\t<div class=\"daexthefu-feedback\">\r\n\t\t\t\t\t<div class=\"daexthefu-text\">\r\n\t\t\t\t\t\t<h3 class=\"daexthefu-title\">War dieser Artikel f\u00fcr dich hilfreich?<\/h3>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"daexthefu-buttons-container\">\r\n\t\t\t\t\t\t<div class=\"daexthefu-buttons\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"daexthefu-yes daexthefu-button daexthefu-button-type-icon\" data-value=\"1\">\r\n\t\t\t\t\r\n                <svg>\r\n                    <defs>\r\n                        <style>.thumb-up-cls-1{fill:#c9c9c9;}.thumb-up-cls-2{fill:#e1e1e1;}.thumb-up-cls-3{fill:#676767;}<\/style>\r\n                    <\/defs>\r\n                    <g id=\"thumb_up\">\r\n                        <path class=\"thumb-up-cls-2 daexthefu-icon-circle\" d=\"m24,3c11.58,0,21,9.42,21,21s-9.42,21-21,21S3,35.58,3,24,12.42,3,24,3m0-1C11.85,2,2,11.85,2,24s9.85,22,22,22,22-9.85,22-22S36.15,2,24,2h0Z\" \/>\r\n                        <g>\r\n                            <rect class=\"thumb-up-cls-3 daexthefu-icon-secondary-color\" x=\"10\" y=\"20\" width=\"6\" height=\"15\" rx=\"1.5\" ry=\"1.5\" \/>\r\n                            <path class=\"thumb-up-cls-1 daexthefu-icon-primary-color\" d=\"m30.57,9.06l-.49-.1c-.81-.17-1.61.35-1.78,1.16l-5.3,11.74c-.17.81,3.16,1.61,3.97,1.78l1.96.41c.81.17,1.61-.35,1.78-1.16l2.18-10.27c.34-1.61-.7-3.21-2.31-3.56Z\" \/>\r\n                            <path class=\"thumb-up-cls-1 daexthefu-icon-primary-color\" d=\"m38.17,20h-18.67c-.83,0-1.5.67-1.5,1.5v12c0,.83.67,1.5,1.5,1.5h16.27c.71,0,1.33-.5,1.47-1.21l2.4-12c.19-.93-.53-1.8-1.47-1.8Z\" \/>\r\n                        <\/g>\r\n                    <\/g>\r\n                <\/svg>\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"daexthefu-no daexthefu-button daexthefu-button-type-icon\" data-value=\"0\">\r\n\t\t\t\t\r\n                <svg>\r\n                    <defs>\r\n                        <style>.thumb-down-cls-1{fill:#c9c9c9;}.thumb-down-cls-2{fill:#e1e1e1;}.thumb-down-cls-3{fill:#676767;}<\/style>\r\n                    <\/defs>\r\n                    <g id=\"thumb_down\">\r\n                        <path class=\"thumb-down-cls-2 daexthefu-icon-circle\" d=\"m24,3c11.58,0,21,9.42,21,21s-9.42,21-21,21S3,35.58,3,24,12.42,3,24,3m0-1C11.85,2,2,11.85,2,24s9.85,22,22,22,22-9.85,22-22S36.15,2,24,2h0Z\" \/>\r\n                        <g>\r\n                            <rect class=\"thumb-down-cls-3 daexthefu-icon-secondary-color\" x=\"10\" y=\"13\" width=\"6\" height=\"15\" rx=\"1.5\" ry=\"1.5\" \/>\r\n                            <path class=\"thumb-down-cls-1 daexthefu-icon-primary-color\" d=\"m30.57,38.94l-.49.1c-.81.17-1.61-.35-1.78-1.16l-5.3-11.74c-.17-.81,3.16-1.61,3.97-1.78l1.96-.41c.81-.17,1.61.35,1.78,1.16l2.18,10.27c.34,1.61-.7,3.21-2.31,3.56Z\" \/>\r\n                            <path class=\"thumb-down-cls-1 daexthefu-icon-primary-color\" d=\"m38.17,28h-18.67c-.83,0-1.5-.67-1.5-1.5v-12c0-.83.67-1.5,1.5-1.5h16.27c.71,0,1.33.5,1.47,1.21l2.4,12c.19.93-.53,1.8-1.47,1.8Z\" \/>\r\n                        <\/g>\r\n                    <\/g>\r\n                <\/svg>\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"daexthefu-comment\">\r\n\t\t\t\t\t<div class=\"daexthefu-comment-top-container\">\r\n\t\t\t\t\t\t<label id=\"daexthefu-comment-label\" class=\"daexthefu-comment-label\"><\/label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"daexthefu-comment-character-counter-container\">\r\n\t\t\t\t\t\t\t\t<div id=\"daexthefu-comment-character-counter-number\"\r\n\t\t\t\t\t\t\t\t\tclass=\"daexthefu-comment-character-counter-number\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"daexthefu-comment-character-counter-text\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<textarea id=\"daexthefu-comment-textarea\" class=\"daexthefu-comment-textarea\"\r\n\t\t\t\t\t\t\t\tplaceholder=\"Dein Feedback\u2026\"\r\n\t\t\t\t\t\t\t\tmaxlength=\"\r\n\t\t\t\t\t\t\t\t500\t\t\t\t\t\t\t\t\t\"><\/textarea>\r\n\t\t\t\t\t<div class=\"daexthefu-comment-buttons-container\">\r\n\t\t\t\t\t\t<button class=\"daexthefu-comment-submit daexthefu-button\">senden<\/button>\r\n\t\t\t\t\t\t<button class=\"daexthefu-comment-cancel daexthefu-button\">abbrechen<\/button>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"daexthefu-successful-submission-text\">Vielen Dank!<\/div>\r\n\r\n\t\t\t<\/div>\r\n\r\n\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Jetzt f\u00fcr 2025 anmelden: Kennenlern- und Ausbildungsbiwak.<\/p>\n","protected":false},"author":1,"featured_media":4536,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"status","meta":{"_helpful_status":1,"inline_featured_image":false,"footnotes":""},"categories":[20],"tags":[208],"class_list":["post-4534","post","type-post","status-publish","format-status","has-post-thumbnail","hentry","category-reserve","tag-biwak","post_format-post-format-status"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leben im Felde &#8226; UNgedient.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leben im Felde &#8226; UNgedient.\" \/>\n<meta property=\"og:description\" content=\"Jetzt f\u00fcr 2025 anmelden: Kennenlern- und Ausbildungsbiwak.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/\" \/>\n<meta property=\"og:site_name\" content=\"UNgedient.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fuchs52y\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/fuchs52y\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-09T11:24:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T08:14:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/biwak-bayern.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/\"},\"author\":{\"name\":\"Daniel\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#\\\/schema\\\/person\\\/1648f47e5e180daeaa9f15f2dd485bf5\"},\"headline\":\"Leben im Felde\",\"datePublished\":\"2024-10-09T11:24:18+00:00\",\"dateModified\":\"2025-10-13T08:14:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/\"},\"wordCount\":918,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/biwak-bayern.jpg\",\"keywords\":[\"biwak\"],\"articleSection\":[\"Reserve\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/\",\"url\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/\",\"name\":\"Leben im Felde &#8226; UNgedient.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/biwak-bayern.jpg\",\"datePublished\":\"2024-10-09T11:24:18+00:00\",\"dateModified\":\"2025-10-13T08:14:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/biwak-bayern.jpg\",\"contentUrl\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/biwak-bayern.jpg\",\"width\":950,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/reserve\\\/leben-im-felde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reserve\",\"item\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/thema\\\/reserve\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Leben im Felde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/\",\"name\":\"UNgedient. Vom Ungedienten zur Bundeswehr.\",\"description\":\"Dein Weg in die Reserve der Bundeswehr\",\"publisher\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#organization\"},\"alternateName\":\"Ausbildung f\u00fcr Ungediente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#organization\",\"name\":\"UNgedient. Vom Ungedienten zur Bundeswehr.\",\"alternateName\":\"Ausbildung Ungedienter zum Reservisten der Bundeswehr\",\"url\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ungedient-favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ungedient-favicon.jpg\",\"width\":520,\"height\":520,\"caption\":\"UNgedient. Vom Ungedienten zur Bundeswehr.\"},\"image\":{\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fuchs52y\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ungedient.de\\\/blog\\\/#\\\/schema\\\/person\\\/1648f47e5e180daeaa9f15f2dd485bf5\",\"name\":\"Daniel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g\",\"caption\":\"Daniel\"},\"description\":\"Daniel absolvierte die Ausbildung f\u00fcr Ungediente 2023 in Rheinland-Pfalz und ist mittlerweile in der 5.\\\/HSchRgt 3 beordert. Er arbeitete als Reservistendienstleistender in einer Projektgruppe des Territorialen F\u00fchrungskommandos der Bundeswehr und engagiert sich als einer von zwei Beauftragten der Landesgruppe Baden-W\u00fcrttemberg des Verbandes der Reservisten der Deutschen Bundeswehr f\u00fcr die Ausbildung Ungediente. 2025 wurde er Vorsitzender der Reservistenarbeitsgemeinschaft Drohne MO. Daniel ist verheiratet und Vater von drei T\u00f6chtern.\",\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/fuchs52y\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leben im Felde &#8226; UNgedient.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/","og_locale":"de_DE","og_type":"article","og_title":"Leben im Felde &#8226; UNgedient.","og_description":"Jetzt f\u00fcr 2025 anmelden: Kennenlern- und Ausbildungsbiwak.","og_url":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/","og_site_name":"UNgedient.","article_publisher":"https:\/\/www.facebook.com\/fuchs52y","article_author":"https:\/\/facebook.com\/fuchs52y","article_published_time":"2024-10-09T11:24:18+00:00","article_modified_time":"2025-10-13T08:14:47+00:00","og_image":[{"width":950,"height":500,"url":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/biwak-bayern.jpg","type":"image\/jpeg"}],"author":"Daniel","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Daniel","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/#article","isPartOf":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/"},"author":{"name":"Daniel","@id":"https:\/\/ungedient.de\/blog\/#\/schema\/person\/1648f47e5e180daeaa9f15f2dd485bf5"},"headline":"Leben im Felde","datePublished":"2024-10-09T11:24:18+00:00","dateModified":"2025-10-13T08:14:47+00:00","mainEntityOfPage":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/"},"wordCount":918,"commentCount":0,"publisher":{"@id":"https:\/\/ungedient.de\/blog\/#organization"},"image":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/#primaryimage"},"thumbnailUrl":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/biwak-bayern.jpg","keywords":["biwak"],"articleSection":["Reserve"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/","url":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/","name":"Leben im Felde &#8226; UNgedient.","isPartOf":{"@id":"https:\/\/ungedient.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/#primaryimage"},"image":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/#primaryimage"},"thumbnailUrl":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/biwak-bayern.jpg","datePublished":"2024-10-09T11:24:18+00:00","dateModified":"2025-10-13T08:14:47+00:00","breadcrumb":{"@id":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/#primaryimage","url":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/biwak-bayern.jpg","contentUrl":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2024\/10\/biwak-bayern.jpg","width":950,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/ungedient.de\/blog\/reserve\/leben-im-felde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ungedient.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Reserve","item":"https:\/\/ungedient.de\/blog\/thema\/reserve\/"},{"@type":"ListItem","position":3,"name":"Leben im Felde"}]},{"@type":"WebSite","@id":"https:\/\/ungedient.de\/blog\/#website","url":"https:\/\/ungedient.de\/blog\/","name":"UNgedient. Vom Ungedienten zur Bundeswehr.","description":"Dein Weg in die Reserve der Bundeswehr","publisher":{"@id":"https:\/\/ungedient.de\/blog\/#organization"},"alternateName":"Ausbildung f\u00fcr Ungediente","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ungedient.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ungedient.de\/blog\/#organization","name":"UNgedient. Vom Ungedienten zur Bundeswehr.","alternateName":"Ausbildung Ungedienter zum Reservisten der Bundeswehr","url":"https:\/\/ungedient.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ungedient.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2023\/03\/ungedient-favicon.jpg","contentUrl":"https:\/\/ungedient.de\/blog\/wp-content\/uploads\/2023\/03\/ungedient-favicon.jpg","width":520,"height":520,"caption":"UNgedient. Vom Ungedienten zur Bundeswehr."},"image":{"@id":"https:\/\/ungedient.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fuchs52y"]},{"@type":"Person","@id":"https:\/\/ungedient.de\/blog\/#\/schema\/person\/1648f47e5e180daeaa9f15f2dd485bf5","name":"Daniel","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ef3cfcfe1a934ab692f6ac8a025998218be6f7edf0973bf6f01a1c8634236232?s=96&d=mm&r=g","caption":"Daniel"},"description":"Daniel absolvierte die Ausbildung f\u00fcr Ungediente 2023 in Rheinland-Pfalz und ist mittlerweile in der 5.\/HSchRgt 3 beordert. Er arbeitete als Reservistendienstleistender in einer Projektgruppe des Territorialen F\u00fchrungskommandos der Bundeswehr und engagiert sich als einer von zwei Beauftragten der Landesgruppe Baden-W\u00fcrttemberg des Verbandes der Reservisten der Deutschen Bundeswehr f\u00fcr die Ausbildung Ungediente. 2025 wurde er Vorsitzender der Reservistenarbeitsgemeinschaft Drohne MO. Daniel ist verheiratet und Vater von drei T\u00f6chtern.","sameAs":["https:\/\/facebook.com\/fuchs52y"]}]}},"_links":{"self":[{"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/posts\/4534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/comments?post=4534"}],"version-history":[{"count":0,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/posts\/4534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/media\/4536"}],"wp:attachment":[{"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/media?parent=4534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/categories?post=4534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ungedient.de\/blog\/wp-json\/wp\/v2\/tags?post=4534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}